{"id":3824,"date":"2020-10-18T19:11:24","date_gmt":"2020-10-18T19:11:24","guid":{"rendered":"https:\/\/bionbweb.eu\/losvalentines\/?post_type=product&#038;p=3824"},"modified":"2024-01-15T16:40:32","modified_gmt":"2024-01-15T16:40:32","slug":"pack-leche-puleva-semidesnatada-precio-unidad","status":"publish","type":"product","link":"https:\/\/bionbweb.eu\/losvalentines\/producto\/pack-leche-puleva-semidesnatada-precio-unidad\/","title":{"rendered":"PACK LECHE PULEVA SEMIDESNATADA <BR> Precio unidad"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":3825,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"_links":{"self":[{"href":"https:\/\/bionbweb.eu\/losvalentines\/wp-json\/wp\/v2\/product\/3824"}],"collection":[{"href":"https:\/\/bionbweb.eu\/losvalentines\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bionbweb.eu\/losvalentines\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bionbweb.eu\/losvalentines\/wp-json\/wp\/v2\/comments?post=3824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bionbweb.eu\/losvalentines\/wp-json\/wp\/v2\/media\/3825"}],"wp:attachment":[{"href":"https:\/\/bionbweb.eu\/losvalentines\/wp-json\/wp\/v2\/media?parent=3824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}