{"id":4324,"date":"2021-04-20T11:14:10","date_gmt":"2021-04-20T11:14:10","guid":{"rendered":"https:\/\/bionbweb.eu\/gourmetfishburgers\/?page_id=4324"},"modified":"2021-04-20T11:14:10","modified_gmt":"2021-04-20T11:14:10","slug":"politica-de-cookies","status":"publish","type":"page","link":"https:\/\/bionbweb.eu\/gourmetfishburgers\/politica-de-cookies\/","title":{"rendered":"Pol\u00edtica de Cookies"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><u>POL\u00cdTICA DE COOKIES<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\">A continuaci\u00f3n encontrar\u00e1s toda la informaci\u00f3n detallada para saber <strong>qu\u00e9<\/strong> son las \u201cCookies\u201d, qu\u00e9 tipos de cookies existen, <strong>qu\u00e9 tipo<\/strong> de cookies utilizamos, y <strong>c\u00f3mo <\/strong>puedes desactivarlas en tu navegador.<\/p>\n<p style=\"text-align: justify;\"><strong><u>\u00bfQu\u00e9 son las cookies?<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\">Son archivos que se pueden descargar en su equipo a trav\u00e9s de las p\u00e1ginas web y permiten almacenar y recuperar informaci\u00f3n sobre los h\u00e1bitos de navegaci\u00f3n de un usuario o de su equipo. Se puede utilizar para mejorar el servicio que se ofrece a trav\u00e9s de la p\u00e1gina y para el reconocimiento del usuario que accede a la misma.<\/p>\n<p style=\"text-align: justify;\"><strong><u>\u00bfQu\u00e9 tipo de cookies existen?<\/u><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>Las cookies propias:<\/strong> son las enviadas al equipo terminal del usuario desde un dominio gestionado por el prestador del servicio solicitado por el usuario.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li><strong>Las cookies de terceros:<\/strong> son aquellas que se env\u00edan al equipo terminal del usuario desde un dominio que no es gestionado por el prestador del servicio solicitado por el usuario, sino que es enviado por otra entidad que trata los datos obtenidos a trav\u00e9s de las cookies.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li><strong>Cookies t\u00e9cnicas:<\/strong> son aquellas que permiten al usuario la navegaci\u00f3n a trav\u00e9s de una p\u00e1gina web, plataforma o aplicaci\u00f3n y la utilizaci\u00f3n de las diferentes opciones o servicios que en ella existan.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li><strong>Cookies de personalizaci\u00f3n:<\/strong> son aquellas que permiten al usuario acceder al servicio con algunas caracter\u00edsticas de car\u00e1cter general predefinidas en funci\u00f3n de una serie de criterios en el terminal del usuario.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li><strong>Cookies de redes sociales externas<\/strong>; la finalidad para la cual se utilizan es para que los visitantes puedan interactuar el contenido de diferentes plataformas sociales.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li><strong>Cookies de an\u00e1lisis:<\/strong> tienen por finalidad recoger informaci\u00f3n an\u00f3nima para llevar a cabo un seguimiento y an\u00e1lisis del comportamiento de los usuarios de los sitios web a los que est\u00e1n vinculados.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong><em>\u00a0<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>Cookies publicitarias<\/strong>: permiten gestionar los espacios publicitarios de una web de la manera m\u00e1s eficaz posible.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li><strong>Cookies de publicidad comportamental<\/strong>: tienen por finalidad observar de manera continuada los h\u00e1bitos de navegaci\u00f3n de los usuarios de una web para desarrollar perfiles espec\u00edficos y mostrar publicidad en funci\u00f3n de los mismos.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li><strong>Cookies de sesi\u00f3n:<\/strong> est\u00e1n preparadas para almacenar datos a la vez que el usuario accede a una p\u00e1gina web.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li><strong>Cookies persistentes:<\/strong> los datos estar\u00e1n almacenados durante el periodo de tiempo definido por el responsable.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong><u>\u00bfQu\u00e9 tipo de cookies utilizamos?<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><u>\u00a0<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\">Navegar por este portal supone que se puedan instalar los siguientes tipos de cookies:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Cookies de mejora de rendimiento.<\/li>\n<li>Cookies de an\u00e1lisis estad\u00edstico.<\/li>\n<li>Cookies de geolocalizaci\u00f3n.<\/li>\n<li>Cookies de registro.<\/li>\n<li>Otras Cookies de terceros.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong><u>\u00bfSe pueden eliminar las cookies?<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\">Se pueden eliminar y bloquear, ya sea de forma general o de forma particular a trav\u00e9s de un dominio espec\u00edfico. Al desactivar las cookies a trav\u00e9s de la configuraci\u00f3n de las opciones del navegador instalado en su equipo, algunos de los servicios podr\u00edan dejar de estar operativos. Hay que adaptar por separado la configuraci\u00f3n de cada navegador y equipo utilizado.<\/p>\n<p style=\"text-align: justify;\">Bloquear o eliminar las cookies instaladas en su equipo mediante la configuraci\u00f3n de las opciones del navegador instalado en su ordenador;<\/p>\n<p style=\"text-align: justify;\"><strong><u>INTERNET EXPLORER<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Primer paso.- <\/strong>Clic en Herramientas y, despu\u00e9s, Opciones de Internet.<\/p>\n<p style=\"text-align: justify;\"><strong>Segundo paso.-<\/strong> Clic en Privacidad y mover el control deslizante hasta el nivel de privacidad deseado y Aceptar.<\/p>\n<p style=\"text-align: justify;\"><strong>Tercer paso.-\u00a0 <\/strong>Internet Explorer indica los tipos de cookies que se bloquean o permiten en cada uno de los niveles de privacidad.<\/p>\n<p style=\"text-align: justify;\"><strong><u>CHROME<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Primer paso.-<\/strong> Men\u00fa y Configuraci\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><strong>Segundo paso.- <\/strong>Clic en Opciones Avanzadas.<\/p>\n<p style=\"text-align: justify;\"><strong>Tercer paso.-<\/strong> \u201cPrivacidad\u201d y clic en Configuraci\u00f3n de contenido.<\/p>\n<p style=\"text-align: justify;\"><strong>Cuarto paso.- <\/strong>Configurar opciones en la secci\u00f3n \u201cCookies\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong><u>FIREFOX<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Primer paso.- <\/strong>Clic en el bot\u00f3n Firefox y Opciones.<\/p>\n<p style=\"text-align: justify;\"><strong>Segundo paso.- <\/strong>Privacidad.<\/p>\n<p style=\"text-align: justify;\"><strong>Tercer paso.-\u00a0 <\/strong>Usar una configuraci\u00f3n personalizada para el historial.<\/p>\n<p style=\"text-align: justify;\"><strong>Cuarto paso.- <\/strong>Aceptar cookies (para su activaci\u00f3n), y desmarcar cookies (para su desactivaci\u00f3n).<\/p>\n<p style=\"text-align: justify;\"><strong>Quinto paso.- <\/strong>Elecci\u00f3n del tiempo de almacenamiento.<\/p>\n<p style=\"text-align: justify;\"><strong>Sexto paso.- <\/strong>Aceptar y cerrar la ventana de Opciones.<\/p>\n<p style=\"text-align: justify;\"><strong><u>SAFARI<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Primer paso.- <\/strong>Preferencias y Privacidad, elige Bloquear Cookies.<\/p>\n<p style=\"text-align: justify;\"><strong>Segundo paso.-<\/strong> Seleccionar la opci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Si desea contactar con nosotros respecto nuestra pol\u00edtica de cookies, puede hacerlo en <a href=\"mailto:info@bionbweb.eu\">info@bionbweb.eu<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>POL\u00cdTICA DE COOKIES A continuaci\u00f3n encontrar\u00e1s toda la informaci\u00f3n detallada para saber qu\u00e9 son las \u201cCookies\u201d, qu\u00e9 tipos de cookies existen, qu\u00e9 tipo de cookies utilizamos, y c\u00f3mo puedes desactivarlas en tu navegador. \u00bfQu\u00e9 son las cookies? Son archivos que se pueden descargar en su equipo a trav\u00e9s de las p\u00e1ginas web y permiten almacenar [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4324","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/bionbweb.eu\/gourmetfishburgers\/wp-json\/wp\/v2\/pages\/4324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bionbweb.eu\/gourmetfishburgers\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bionbweb.eu\/gourmetfishburgers\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bionbweb.eu\/gourmetfishburgers\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/bionbweb.eu\/gourmetfishburgers\/wp-json\/wp\/v2\/comments?post=4324"}],"version-history":[{"count":1,"href":"https:\/\/bionbweb.eu\/gourmetfishburgers\/wp-json\/wp\/v2\/pages\/4324\/revisions"}],"predecessor-version":[{"id":4325,"href":"https:\/\/bionbweb.eu\/gourmetfishburgers\/wp-json\/wp\/v2\/pages\/4324\/revisions\/4325"}],"wp:attachment":[{"href":"https:\/\/bionbweb.eu\/gourmetfishburgers\/wp-json\/wp\/v2\/media?parent=4324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}